{"id":200,"count":1,"description":"","link":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/","name":"Haydn","slug":"haydn-digital-downloads","taxonomy":"product_cat","parent":188,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Haydn Archives - UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haydn Archives - UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/\" \/>\n<meta property=\"og:site_name\" content=\"UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/product-category\\\/digital-downloads\\\/composer-digital-downloads\\\/haydn-digital-downloads\\\/\",\"url\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/product-category\\\/digital-downloads\\\/composer-digital-downloads\\\/haydn-digital-downloads\\\/\",\"name\":\"Haydn Archives - UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/product-category\\\/digital-downloads\\\/composer-digital-downloads\\\/haydn-digital-downloads\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/product-category\\\/digital-downloads\\\/composer-digital-downloads\\\/haydn-digital-downloads\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digital Downloads\",\"item\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/product-category\\\/digital-downloads\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Composer\",\"item\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/product-category\\\/digital-downloads\\\/composer-digital-downloads\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Haydn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/\",\"name\":\"UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/#organization\",\"name\":\"Ultra Analogue Recordings\",\"url\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ultra-logo.png\",\"contentUrl\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ultra-logo.png\",\"width\":369,\"height\":127,\"caption\":\"Ultra Analogue Recordings\"},\"image\":{\"@id\":\"https:\\\/\\\/ultraanaloguerecordings.com\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1uKUiHH3nxyHEiyvyVTdzw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Haydn Archives - UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/","og_locale":"en_US","og_type":"article","og_title":"Haydn Archives - UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music","og_url":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/","og_site_name":"UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/","url":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/","name":"Haydn Archives - UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music","isPartOf":{"@id":"https:\/\/ultraanaloguerecordings.com\/new\/#website"},"breadcrumb":{"@id":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/#breadcrumb"},"inLanguage":"en-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/haydn-digital-downloads\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ultraanaloguerecordings.com\/new\/"},{"@type":"ListItem","position":2,"name":"Digital Downloads","item":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/"},{"@type":"ListItem","position":3,"name":"Composer","item":"https:\/\/ultraanaloguerecordings.com\/new\/product-category\/digital-downloads\/composer-digital-downloads\/"},{"@type":"ListItem","position":4,"name":"Haydn"}]},{"@type":"WebSite","@id":"https:\/\/ultraanaloguerecordings.com\/new\/#website","url":"https:\/\/ultraanaloguerecordings.com\/new\/","name":"UltraAnalogue Recordings | Toronto Analogue Recordings of Classical Music","description":"","publisher":{"@id":"https:\/\/ultraanaloguerecordings.com\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ultraanaloguerecordings.com\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/ultraanaloguerecordings.com\/new\/#organization","name":"Ultra Analogue Recordings","url":"https:\/\/ultraanaloguerecordings.com\/new\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/ultraanaloguerecordings.com\/new\/#\/schema\/logo\/image\/","url":"https:\/\/ultraanaloguerecordings.com\/new\/wp-content\/uploads\/2017\/06\/ultra-logo.png","contentUrl":"https:\/\/ultraanaloguerecordings.com\/new\/wp-content\/uploads\/2017\/06\/ultra-logo.png","width":369,"height":127,"caption":"Ultra Analogue Recordings"},"image":{"@id":"https:\/\/ultraanaloguerecordings.com\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UC1uKUiHH3nxyHEiyvyVTdzw"]}]}},"_links":{"self":[{"href":"https:\/\/ultraanaloguerecordings.com\/new\/wp-json\/wp\/v2\/product_cat\/200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultraanaloguerecordings.com\/new\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ultraanaloguerecordings.com\/new\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ultraanaloguerecordings.com\/new\/wp-json\/wp\/v2\/product_cat\/188"}],"wp:post_type":[{"href":"https:\/\/ultraanaloguerecordings.com\/new\/wp-json\/wp\/v2\/product?product_cat=200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}